{"id":2527,"date":"2016-09-19T10:00:40","date_gmt":"2016-09-19T08:00:40","guid":{"rendered":"http:\/\/coisasnovas.skokka.com\/?p=2527"},"modified":"2025-05-04T09:17:40","modified_gmt":"2025-05-04T12:17:40","slug":"ta-na-rede-peixe","status":"publish","type":"post","link":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/","title":{"rendered":"T\u00e1 na rede \u00e9 peixe!"},"content":{"rendered":"<p>Bom dia!!!<\/p>\n<p>5 palavras e um significado. Quem nunca? N\u00e3o \u00e9 mesmo? Estava olhando alguns an\u00fancios em Skokka.com e me deparei com essa express\u00e3o t\u00e3o conhecida, pouco utilizada, mas sempre compreendida.<\/p>\n<p>&nbsp;<\/p>\n<p>Se antigamente, os homens n\u00e3o escolhiam as mulheres que ia &#8220;pescar&#8221; na balada&#8230; agora s\u00e3o elas que utilizam dessa n\u00e3o estrat\u00e9gia&#8230; pois \u00e9.<\/p>\n<p><a href=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/SAM_1547.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2528\" src=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/SAM_1547.jpg\" alt=\"sam_1547\" width=\"840\" height=\"594\" \/><\/a><\/p>\n<p>Muitas v\u00e3o pras boates, ficam entre bar e pista de dan\u00e7a pra fisgar o primeiro que aparecer&#8230; seja convidando pra uma caipivodka, seja para dan\u00e7ar.<\/p>\n<p>E por que ser\u00e1 que utilizamos o peixe como refer\u00eancia? E a rede? Por que n\u00e3o: mel e abelha? Beija-flor e a flor&#8230; hahahahaha por que ser\u00e1 que usamos um animal sem qualquer sensualidade ou meiguice? \u00a0Sei l\u00e1&#8230; sempre vi essa express\u00e3o um tanto asquerosa&#8230;<\/p>\n<p style=\"text-align: justify\">Me escrevam, fa\u00e7am um sinal de fuma\u00e7a\u00a0e\u00a0me enviem email com sugest\u00f5es: <strong>&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;lacommunity@skokka.com<\/strong><\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/twitter.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-956\" src=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/twitter.png\" alt=\"twitter\" width=\"33\" height=\"33\" \/><\/a>Em twitter com a\u00a0Hashtag <b>#AEstagiaria<\/b><\/p>\n<p style=\"text-align: justify\"><em><a href=\"http:\/\/twitter.com\/Skokka_Latam\" target=\"_blank\" rel=\"noopener noreferrer\">@SKOKKA_LATAM<\/a>\u00a0\u00a0<\/em><em>\u00a0<a href=\"http:\/\/twitter.com\/Skokka_ES\" target=\"_blank\" rel=\"noopener noreferrer\">@SKOKKA_ES<\/a>\u00a0 <\/em><em>\u00a0<a href=\"http:\/\/twitter.com\/Skokka_BR\" target=\"_blank\" rel=\"noopener noreferrer\">@SKOKKA_BR<\/a><\/em><\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/facebook.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-954\" src=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/facebook.png\" alt=\"facebook\" width=\"33\" height=\"33\" \/><\/a>No\u00a0Facebook<\/p>\n<p style=\"text-align: justify\"><em>\u00a0<a href=\"https:\/\/www.facebook.com\/Skokka-Latinoam%C3%A9rica-959700397424096\/?fref=ts\" target=\"_blank\" rel=\"noopener noreferrer\">Skokka Latinoam\u00e9rica<\/a>\u00a0\u00a0\u00a0 \u00a0\u00a0<a href=\"https:\/\/www.facebook.com\/Skokka-Espa%C3%B1a-1445527905690433\/?fref=ts\" target=\"_blank\" rel=\"noopener noreferrer\">Skokka Espa\u00f1a<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<a href=\"https:\/\/www.facebook.com\/SkokkaBrasil\/?ref=hl\" target=\"_blank\" rel=\"noopener noreferrer\">Skokka Brasil<\/a><\/em><\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/instagram.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-955\" src=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2020\/01\/instagram.png\" alt=\"instagram\" width=\"33\" height=\"33\" \/><\/a>No\u00a0Instagram como <strong>#AEstagiaria<\/strong><\/p>\n<p style=\"text-align: justify\"><em><a href=\"http:\/\/instagram.com\/skokka_latam\" target=\"_blank\" rel=\"noopener noreferrer\">Skokka Latinoam\u00e9rica<\/a>\u00a0\u00a0\u00a0 \u00a0\u00a0<a href=\"http:\/\/instagram.com\/skokka_espana\" target=\"_blank\" rel=\"noopener noreferrer\">Skokka Espa\u00f1a<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<a href=\"http:\/\/instagram.com\/skokka_br\" target=\"_blank\" rel=\"noopener noreferrer\">Skokka Brasil<\/a><\/em><\/p>\n<p style=\"text-align: justify\">\u2764\ufe0f\u200d\u2764\ufe0f\u200d\u2764\ufe0f\u200d Muaaaaa \u2764\ufe0f\u200d\u2764\ufe0f\u200d\u2764\ufe0f\u200d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bom dia!!! 5 palavras e um significado. Quem nunca? N\u00e3o \u00e9 mesmo? Estava olhando alguns an\u00fancios em Skokka.com e me deparei com essa express\u00e3o t\u00e3o conhecida, pouco utilizada, mas sempre compreendida. &nbsp; Se antigamente, os homens n\u00e3o escolhiam as mulheres que ia &#8220;pescar&#8221; na balada&#8230; agora s\u00e3o elas que utilizam dessa n\u00e3o estrat\u00e9gia&#8230; pois \u00e9. [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":2528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relacionamentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e1 na rede \u00e9 peixe! - Blog oficial do Skokka<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e1 na rede \u00e9 peixe! - Blog oficial do Skokka\" \/>\n<meta property=\"og:description\" content=\"Bom dia!!! 5 palavras e um significado. Quem nunca? N\u00e3o \u00e9 mesmo? Estava olhando alguns an\u00fancios em Skokka.com e me deparei com essa express\u00e3o t\u00e3o conhecida, pouco utilizada, mas sempre compreendida. &nbsp; Se antigamente, os homens n\u00e3o escolhiam as mulheres que ia &#8220;pescar&#8221; na balada&#8230; agora s\u00e3o elas que utilizam dessa n\u00e3o estrat\u00e9gia&#8230; pois \u00e9. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog oficial do Skokka\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61586204562072\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-19T08:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-04T12:17:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2026\/04\/image-18.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Martina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Skokka_BR\" \/>\n<meta name=\"twitter:site\" content=\"@Skokka_BR\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/\"},\"author\":{\"name\":\"Martina\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#\\\/schema\\\/person\\\/59f957fe93ba0b0204614474face4fab\"},\"headline\":\"T\u00e1 na rede \u00e9 peixe!\",\"datePublished\":\"2016-09-19T08:00:40+00:00\",\"dateModified\":\"2025-05-04T12:17:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/\"},\"wordCount\":203,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Relacionamentos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/\",\"url\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/\",\"name\":\"T\u00e1 na rede \u00e9 peixe! - Blog oficial do Skokka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-09-19T08:00:40+00:00\",\"dateModified\":\"2025-05-04T12:17:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/2016\\\/09\\\/ta-na-rede-peixe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e1 na rede \u00e9 peixe!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/\",\"name\":\"Blog oficial do Skokka\",\"description\":\"Skokka Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#organization\",\"name\":\"Skokka\",\"url\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/logo_skokka-1.png\",\"contentUrl\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/logo_skokka-1.png\",\"width\":300,\"height\":300,\"caption\":\"Skokka\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61586204562072\",\"https:\\\/\\\/x.com\\\/Skokka_BR\",\"https:\\\/\\\/www.tiktok.com\\\/@skokkabrasil\",\"https:\\\/\\\/www.instagram.com\\\/skk_news\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.skokka.com\\\/br\\\/#\\\/schema\\\/person\\\/59f957fe93ba0b0204614474face4fab\",\"name\":\"Martina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab7710d80be2c4c07129931b999ee475f976136b106a5fa262ba72900adbb87?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab7710d80be2c4c07129931b999ee475f976136b106a5fa262ba72900adbb87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bab7710d80be2c4c07129931b999ee475f976136b106a5fa262ba72900adbb87?s=96&d=mm&r=g\",\"caption\":\"Martina\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e1 na rede \u00e9 peixe! - Blog oficial do Skokka","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/","og_locale":"pt_BR","og_type":"article","og_title":"T\u00e1 na rede \u00e9 peixe! - Blog oficial do Skokka","og_description":"Bom dia!!! 5 palavras e um significado. Quem nunca? N\u00e3o \u00e9 mesmo? Estava olhando alguns an\u00fancios em Skokka.com e me deparei com essa express\u00e3o t\u00e3o conhecida, pouco utilizada, mas sempre compreendida. &nbsp; Se antigamente, os homens n\u00e3o escolhiam as mulheres que ia &#8220;pescar&#8221; na balada&#8230; agora s\u00e3o elas que utilizam dessa n\u00e3o estrat\u00e9gia&#8230; pois \u00e9. [...]","og_url":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/","og_site_name":"Blog oficial do Skokka","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61586204562072","article_published_time":"2016-09-19T08:00:40+00:00","article_modified_time":"2025-05-04T12:17:40+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2026\/04\/image-18.png","type":"image\/png"}],"author":"Martina","twitter_card":"summary_large_image","twitter_creator":"@Skokka_BR","twitter_site":"@Skokka_BR","twitter_misc":{"Escrito por":"Martina","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#article","isPartOf":{"@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/"},"author":{"name":"Martina","@id":"https:\/\/blog.skokka.com\/br\/#\/schema\/person\/59f957fe93ba0b0204614474face4fab"},"headline":"T\u00e1 na rede \u00e9 peixe!","datePublished":"2016-09-19T08:00:40+00:00","dateModified":"2025-05-04T12:17:40+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/"},"wordCount":203,"commentCount":3,"publisher":{"@id":"https:\/\/blog.skokka.com\/br\/#organization"},"image":{"@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#primaryimage"},"thumbnailUrl":"","articleSection":["Relacionamentos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/","url":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/","name":"T\u00e1 na rede \u00e9 peixe! - Blog oficial do Skokka","isPartOf":{"@id":"https:\/\/blog.skokka.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#primaryimage"},"image":{"@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-09-19T08:00:40+00:00","dateModified":"2025-05-04T12:17:40+00:00","breadcrumb":{"@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.skokka.com\/br\/2016\/09\/ta-na-rede-peixe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.skokka.com\/br\/"},{"@type":"ListItem","position":2,"name":"T\u00e1 na rede \u00e9 peixe!"}]},{"@type":"WebSite","@id":"https:\/\/blog.skokka.com\/br\/#website","url":"https:\/\/blog.skokka.com\/br\/","name":"Blog oficial do Skokka","description":"Skokka Brasil","publisher":{"@id":"https:\/\/blog.skokka.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.skokka.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.skokka.com\/br\/#organization","name":"Skokka","url":"https:\/\/blog.skokka.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.skokka.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2017\/11\/logo_skokka-1.png","contentUrl":"https:\/\/blog.skokka.com\/br\/wp-content\/uploads\/sites\/2\/2017\/11\/logo_skokka-1.png","width":300,"height":300,"caption":"Skokka"},"image":{"@id":"https:\/\/blog.skokka.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61586204562072","https:\/\/x.com\/Skokka_BR","https:\/\/www.tiktok.com\/@skokkabrasil","https:\/\/www.instagram.com\/skk_news\/"]},{"@type":"Person","@id":"https:\/\/blog.skokka.com\/br\/#\/schema\/person\/59f957fe93ba0b0204614474face4fab","name":"Martina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/bab7710d80be2c4c07129931b999ee475f976136b106a5fa262ba72900adbb87?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bab7710d80be2c4c07129931b999ee475f976136b106a5fa262ba72900adbb87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bab7710d80be2c4c07129931b999ee475f976136b106a5fa262ba72900adbb87?s=96&d=mm&r=g","caption":"Martina"}}]}},"_links":{"self":[{"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/posts\/2527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/comments?post=2527"}],"version-history":[{"count":1,"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/posts\/2527\/revisions"}],"predecessor-version":[{"id":13272,"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/posts\/2527\/revisions\/13272"}],"wp:attachment":[{"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/media?parent=2527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/categories?post=2527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.skokka.com\/br\/wp-json\/wp\/v2\/tags?post=2527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}